{"id":4925,"date":"2017-12-10T10:00:00","date_gmt":"2017-12-10T09:00:00","guid":{"rendered":"https:\/\/wetourtheworld.com\/?p=4925"},"modified":"2026-08-12T08:44:29","modified_gmt":"2026-08-12T06:44:29","slug":"queenstown-abenteuerhauptstadt","status":"publish","type":"post","link":"https:\/\/wetourtheworld.com\/de\/queenstown-abenteuerhauptstadt\/","title":{"rendered":"Queenstown: Neuseelands Abenteuerhauptstadt"},"content":{"rendered":"\n<center><!-- Copy & Pasted from YouTube --><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/znt7FcyVrtA?rel=0&amp;vq=hd720;showinfo=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/center>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queenstown ist Neuseelands Abenteuerhauptstadt Nr. 1. Nicht ohne Grund geh\u00f6rte die S\u00fcdinsel zu den ersten Orten, an denen Bungee Jumping kommerziell angeboten wurde. Wenn Du entspannte Tage am See verbringen m\u00f6chtest, f\u00e4hrst Du besser nach Wanaka. Auch Queenstown liegt wundersch\u00f6n an einem See, dem Lake Wakatipu. Er ist Neuseelands drittgr\u00f6\u00dfter See und einer der klarsten \/ blauesten, die wir je gesehen haben. Der Ort selbst ist allerdings sehr touristisch und im Sommer \/ in der Hochsaison voller Abenteuersuchender. \u00dcberall findest Du Touranbieter mit verr\u00fcckten Bungee Jumps, Rafting-Touren, Canyon Swings und vielen weiteren Aktivit\u00e4ten, die Deinen Puls in die H\u00f6he treiben. Dazu kommen unz\u00e4hlige Bars, Restaurants, Caf\u00e9s und Shops. Bei uns war es keine Liebe auf den ersten Blick. Als wir Queenstown 2015 besuchten, fanden wir es viel zu voll und flohen nach nicht einmal einem Tag. Diesmal genossen wir es richtig und werden definitiv zur\u00fcckkommen!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" class=\"wp-image-5261\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-3.jpg\" alt=\"Queenstown am fr\u00fchen Morgen vor den umliegenden Bergen\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-3.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-3-300x200.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-3-768x512.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-3-705x470.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Shotover Canyon Swing &amp; Canyon Fox<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach unserer Ankunft in Queenstown gingen wir direkt zu <strong>\u201eShotover Canyon Swing &amp; Canyon Fox\u201c<\/strong>, um einen Canyon Swing zu buchen. Auch andere Anbieter wie AJ Hackett verkaufen solche Spr\u00fcnge, dort gibt es sogar den h\u00f6chsten. Weil uns das B\u00fcro und die freundlichen Mitarbeiter bei Shotover gefielen, buchten wir aber sofort dort. Bianca wollte diesen Swing unbedingt machen, seit sie einen Clip auf Facebook gesehen hatte. Er ist hoch und fast wie Bungee Jumping. Das hatte es wegen ihrer ernsthaften H\u00f6henangst und dem kopf\u00fcber H\u00e4ngen nie auf ihre Abenteuerliste geschafft. Beim Canyon Swing h\u00e4ngst Du aber nicht an den F\u00fc\u00dfen, sondern in einem Gurt um die Taille. Dieser Unterschied reichte Bianca. Ansonsten ist die Aktivit\u00e4t hoch (110 Meter \/ 360 ft), Du springst \u00fcber dem Shotover River von einer Klippe und f\u00e4llst 60 senkrechte Meter lang f\u00fcr 4 Sekunden frei. Im Grunde ist also alles, wovor sie Angst hat, in einer Aktivit\u00e4t vereint. Genau im Moment der Buchung fand sie die Idee zwar noch cool, entschied aber gleichzeitig, dass etwas so Hohes und Bungee-\u00c4hnliches eigentlich nichts war, was sie wirklich tun wollte. Zum Gl\u00fcck denkt Bianca nie lange nach, bevor sie etwas macht, vor dem sie Angst haben k\u00f6nnte. So hat sie schon viele Dinge getan, die ihr h\u00f6llische Angst machten: <a href=\"https:\/\/wetourtheworld.com\/de\/lesotho-semonkong-maletsunyane-sani-pass\/\">204 Meter an einem Wasserfall abseilen<\/a>, also hoch, Skydiving, hoch und mit freiem Fall, und Canyoning in den Waitomo Caves, dunkel, kalt und eng.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" class=\"wp-image-5262\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-3.jpg\" alt=\"Plattform des Shotover Canyon Swing \u00fcber der bewaldeten Schlucht\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-3.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-3-300x200.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-3-768x512.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-3-705x470.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Shotover bietet au\u00dferdem den Canyon Fox an, im Grunde eine extrem hohe und lange Zipline mit Freifall-Element (180 Meter hoch und insgesamt 445 Meter lang \u00fcber die beiden Seile). Wenn Du lieber die gro\u00dfartige Aussicht auf den Canyon genie\u00dfen m\u00f6chtest und nicht so sehr auf freien Fall und Herumh\u00e4ngen an einem Seil stehst, solltest Du definitiv die Zipline nehmen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">In Ferg we Trust: der beste Burger in (Queens)Town<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bevor es zu dieser adrenalingeladenen Aktivit\u00e4t ging, brauchte Bianca eine Ablenkung von der Tatsache, dass sie bald etwas Hohes mit freiem Fall machen w\u00fcrde. Also g\u00f6nnten wir uns etwas, das unser knappes Weltreisebudget nicht oft erlaubt: ausw\u00e4rts essen. Genauer gesagt einen <strong>Fergburger<\/strong>. Das Restaurant ist eine echte Institution in Queenstown und auf Gourmet-Hamburger spezialisiert. Bianca liebt Hamburger. Nun ja, sie liebt alles, was irgendwie mit den Vereinigten Staaten von Amerika zu tun hat, dort beliebt ist oder von dort kommt. Sie beginnt sogar zu weinen, wenn sie die Nationalhymne h\u00f6rt. Sie ist also ein echter Fan. Fergburger geh\u00f6rt definitiv zu den besten Burgern der Welt. Wir haben in unserem Leben sehr viele probiert und finden, dass er wirklich einer der besten ist. Bianca entschied allerdings, dass es den einen besten Burger gar nicht gibt, weil es so viele richtig gute gibt: Five Guys, In-N-Out Burger und Burger Joint in den USA, Kirby&#8217;s und Freigeist zu Hause in Graz und so weiter. Es ist also nicht wie bei Nutella, dem besten Haselnussaufstrich der Welt, sondern eher wie bei Schokolade und franz\u00f6sischen Macarons. Gute Exemplare findest Du \u00fcberall auf der Welt.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" class=\"wp-image-5264\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-2.jpg\" alt=\"Menschen warten vor dem Fergburger in Queenstown\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-2.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-2-300x200.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-2-768x512.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-2-705x470.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Als wir 2015 in Queenstown waren, gingen wir ebenfalls dorthin. Toms Freund Reini, der ein Austauschsemester in Neuseeland verbracht hatte, empfahl uns den Laden. Schon als wir uns dem kleinen Restaurant n\u00e4herten, bemerkten wir eine lange Schlange und fragten uns verwirrt, welcher Shop gerade was gratis verteilte. Als wir n\u00e4her kamen, h\u00f6rten wir bereits die Stimme eines M\u00e4dchens im \u201eFergburger\u201c-Shirt, das uns \u00fcber die aktuelle Lage informierte: Die Wartezeit bis zur Bestellung betr\u00e4gt 1 Stunde 20 Minuten, danach dauert es etwa 45 Minuten, bis das Essen kommt. Bianca begann zu lachen, weil sie es f\u00fcr einen Witz hielt, doch das M\u00e4dchen meinte es ernst. Es war Mittag, brennend hei\u00df, die Schlange lag nicht im Schatten, und das Schlimmste war, dass wir wirklich hungrig waren. Also gingen wir, ohne den ber\u00fchmten Fergburger probiert zu haben.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" class=\"wp-image-5263\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-1.jpg\" alt=\"G\u00e4ste unter blauen Schirmen vor dem Fergburger\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-1.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-1-300x200.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-1-768x512.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Fergburger-1-705x470.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Diesmal wussten wir, was uns erwartete, und waren fest entschlossen. Egal wie lange es dauern w\u00fcrde, wir w\u00fcrden warten. Vor dem Restaurant gab es wieder eine Schlange, sie war aber bei Weitem nicht so lang wie zwei Jahre zuvor. Kaum hatten wir unsere hungrigen K\u00f6rper ans Ende gestellt, h\u00f6rten wir die vertraute Ansage: 20 Minuten bis zur Bestellung, danach etwa 20 \/ 25 Minuten bis zum Essen. Gro\u00dfartig, nur 50 Minuten. Dann w\u00fcrden wir endlich den ber\u00fchmten Burger genie\u00dfen. Das M\u00e4dchen gab uns die Speisekarte, und wir verk\u00fcrzten uns die Wartezeit mit der Auswahl. Tom entschied sich f\u00fcr den <strong>Fergberger Deluxe<\/strong> mit erstklassigem Rindfleisch, Bacon, Cheddar, Essiggurke, Salat, Tomate, roter Zwiebel sowie Aioli &amp; Tomatenrelish. Bianca bestellte <strong>The Fergburger<\/strong> mit Rindfleisch, Salat, Tomate, Cheddar und nat\u00fcrlich ohne Zwiebel und Relish. Beide nahmen Pommes dazu. Wir hatten gro\u00dfes Gl\u00fcck und ergatterten einen der wenigen Tische vor dem Restaurant. Falls Du keinen bekommst, kannst Du Deinen Burger auf einer Bank vor dem Restaurant, in einem nahe gelegenen Park oder an der Uferpromenade des Lake Wakatipu genie\u00dfen. Sie ist nur 3 Minuten vom Fergburger entfernt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">25 Minuten sp\u00e4ter erschien unsere Bestellnummer auf der Anzeige. Vom Anstellen bis zum fertigen Burger dauerte es insgesamt 50 Minuten. F\u00fcr einen Fergburger ist das wirklich Fast Food. Wir packten die Burger aus, holten die Pommes hervor und \u00f6ffneten den Aioli-Dip. Es war eine echte Zeremonie. Die Burger waren k\u00f6stlich: saftiges Fleisch, frisches Gem\u00fcse und einfach perfektes Brot. Die Pommes waren genauso gut und der Aioli-Dip \u2026 ja, auch perfekt. Wir a\u00dfen alles auf. Die Portionen sind wirklich gro\u00df und jeden einzelnen Dollar wert. Wenn Du dort ankommst und vor einer langen Schlange stehst, kannst Du Dich entweder anstellen oder sp\u00e4ter wiederkommen. Fergberger hat von 8:00 AM bis 5:00 AM ge\u00f6ffnet. In diesem Fall sagt ein Video mehr als 1,000 Worte. Sieh Dir also unbedingt unseren VLOG \u00fcber den k\u00f6stlichen Fergberger an:<br>\n&nbsp;<\/p>\n\n\n\n<center><!-- Copy & Pasted from YouTube --><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/iTqJhh9bY6M?rel=0&amp;vq=hd720\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/center>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direkt neben dem Fergburger befindet sich der <strong>Fergbaker<\/strong>, der alle m\u00f6glichen Brotsorten und s\u00fc\u00dfes Geb\u00e4ck wie Croissants, Pains au Chocolat, Donuts und Plundergeb\u00e4ck verkauft. Nat\u00fcrlich gibt es auch Kaffee, deshalb ist es der richtige Ort f\u00fcr ein schnelles Fr\u00fchst\u00fcck. Ge\u00f6ffnet ist von 6:30 AM bis 4:30 AM, also im Grunde fast immer. Perfekt f\u00fcr einen schnellen Snack vor einer morgendlichen Tour oder nach einer Partynacht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Du lieber entspannt einen Kaffee oder eine hei\u00dfe Schokolade mit malerischer Aussicht genie\u00dfen m\u00f6chtest, kannst Du auch zu <strong>Patagonia Chocolates<\/strong> gehen. Das sehr nette Caf\u00e9 hat 2 Standorte im Zentrum von Queenstown (f\u00fcr G\u00e4ste gibt es kostenloses WIFI, frag an der Kasse einfach nach einem Gutschein). Queenstown hat au\u00dferdem einen <strong>Starbucks<\/strong> mit kostenlosem WIFI und Steckdosen f\u00fcr Laptops \/ Handys \/ Tablets. Wir fanden das WIFI bei Starbucks am besten, obwohl die Verbindung manchmal abbrach. Die blo\u00dfe Existenz von Steckdosen ist allerdings ein so gro\u00dfer Vorteil, dass wir unseren Kaffee meistens bei Starbucks tranken.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Canyon Swing am Shotover River<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201eDas ist keine Teeparty bei der Gro\u00dfmutter.\u201c<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da sa\u00dfen wir also im Shuttlebus zum Canyon. Es war sehr fr\u00fch am Morgen, unsere Tour begann um 8:30 AM, und Biancas H\u00e4nde waren ziemlich feucht. Sie hatte trotzdem beschlossen, dass dies eines der coolsten Dinge werden w\u00fcrde, die sie je getan hatte. Gut m\u00f6glich, dass der n\u00e4chste Schritt Bungee Jumping ist, obwohl sie das mit Sicherheit niemals in ihrem ganzen Leben machen wird. 15 Minuten vor Beginn musst Du im B\u00fcro von <a href=\"http:\/\/canyonswing.co.nz\/\" target=\"_blank\" rel=\"noopener\">Shotover Canyon Swing &amp; Fox<\/a> sein. Wir kamen also um 8:15 AM mit einem Donut und einem Kaffee vom Fergbaker an. Dein Guide begr\u00fc\u00dft und wiegt Dich, weil Du f\u00fcr die Teilnahme ein bestimmtes Gewicht nicht \u00fcberschreiten darfst. Keine Sorge, die Zahl wird Dir nicht verraten J. Danach geht es los. Der Shuttlebus braucht etwa 20 Minuten bis zum Canyon. Zum Entspannen oder \u00dcberdenken Deiner Entscheidung bleibt w\u00e4hrend der Fahrt allerdings keine Zeit. Stattdessen siehst Du ein Video mit allen Swing-Varianten, damit Du Dich bis zur Ankunft an der Plattform entschieden hast.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" class=\"wp-image-5266\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-2.jpg\" alt=\"Shotover Canyon Swing \u00fcber dem t\u00fcrkisfarbenen Fluss\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-2.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-2-300x200.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-2-768x512.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-2-705x470.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Wir entschieden uns f\u00fcr den Tandem Swing und sprangen gemeinsam. Tom hatte die Ehre, die Variante auszuw\u00e4hlen. Es gibt viele M\u00f6glichkeiten, und er entschied sich f\u00fcr den <strong>Backward Tandem Jump<\/strong>. Alle Sprungstile werden nach dem Shotover Rating System mit einer bis f\u00fcnf beschissenen Unterhosen bewertet. Der Backward Tandem Jump bekommt f\u00fcnf und damit die h\u00f6chste Gruselbewertung. Auch Deine Schei\u00dfe wird v\u00f6llig ver\u00e4ngstigt sein. Wenn Du unsere gl\u00fccklichen Gesichter sehen m\u00f6chtest, w\u00e4hrend wir die Klippe hinunterfallen, dr\u00fcck einfach unten auf Play:<br>\n&nbsp;<\/p>\n\n\n\n<center><!-- Copy & Pasted from YouTube --><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/znt7FcyVrtA?rel=0&amp;vq=hd720\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/center>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<br>\n<strong>Hier ist eine Auswahl aus dem \u201eMen\u00fc\u201c der Sprungstile:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Forwards Jump<\/em> \u2013 Du gehst oder l\u00e4ufst zur Kante und springst (3 Unterhosen)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>The Chair Jump<\/em> \u2013 Du wirst an einem Stapel aus drei St\u00fchlen befestigt (sitzt also im Grunde), ein Mitarbeiter h\u00e4lt Dich fest und l\u00e4sst Dich dann r\u00fcckw\u00e4rts \u00fcber die Kante fallen (3 Unterhosen)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>The Slide Jump<\/em> \u2013 Biancas Favorit (den m\u00f6chte sie beim n\u00e4chsten Mal machen), dabei wird eine Rutsche an der Plattform befestigt, \u00fcber die Du in den freien Fall rutschst (3 Unterhosen)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Indian Rope Trick Jump<\/em> \u2013 Du h\u00e4ltst Dich so lange an einem Seil fest, wie Deine Muskeln durchhalten. Wenn Du nicht mehr kannst, f\u00e4llst Du hinunter (4 Unterhosen)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gimp Boy goes to Hollywood<\/em> \u2013 Du wirst kopf\u00fcber \u00fcber dem Canyon aufgeh\u00e4ngt, die Mitarbeiter l\u00f6sen Dich, indem sie ein Seil durchschneiden (5 Unterhosen)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Shotover Canyon Swing<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kosten pro Person: NZD 239 pro Person (rund 140 EUR)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Tour beinhaltet den Shuttlebus und die gesamte Ausr\u00fcstung<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferdem bekommst Du den zweiten Sprung f\u00fcr NZD 45, und zwar nicht nur am Tag Deines Sprungs, sondern lebenslang. Wann immer Du nach Queenstown zur\u00fcckkehrst, kannst Du ihn also f\u00fcr nur 45 Dollar erneut machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sicherheit:<\/strong> Wir f\u00fchlten uns sehr sicher. Unser Guide erkl\u00e4rte uns alles, worauf wir achten mussten und was beim Sprung von der Klippe wichtig war<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf der Sprungplattform arbeiten viele Mitarbeiter: ein Mann, der Dir den Gurt anlegt und pr\u00fcft, ob alles perfekt sitzt, sowie zwei M\u00e4nner, die Dich auf der Plattform auf den Sprung vorbereiten (Dich sichern, Tipps zur besten Sprungweise f\u00fcr Deinen gew\u00e4hlten Stil geben, erkl\u00e4ren, woran Du denken sollst, und ein wirklich sicheres Gef\u00fchl vermitteln).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mitarbeiter:<\/strong> Das Team von Shotover war sehr freundlich und hilfsbereit. Wir f\u00fchlten uns willkommen und nicht wie die 1.000. Personen, die diesen Swing machten. Du sp\u00fcrst, dass sie ihre Arbeit lieben und ihre Begeisterung gern mit anderen Abenteuersuchenden teilen.<\/p>\n\n\n\n<aside class=\"wttw-affiliate-card\" data-affiliate-provider=\"getyourguide\" aria-label=\"Option zur Tourbuchung\">\n\t<span class=\"wttw-affiliate-card__eyebrow\">Touroption<\/span>\n\t<p class=\"wttw-affiliate-card__title\">Shotover Canyon Swing<\/p>\n\t<p class=\"wttw-affiliate-card__copy\">Wir haben diesen Canyon Swing selbst gemacht und liebten, wie sehr das Team seine Begeisterung f\u00fcr das Erlebnis teilte. Aktuelle Termine und Preise sind online verf\u00fcgbar.<\/p>\n\t<a class=\"wttw-button wttw-affiliate-card__button\" href=\"https:\/\/www.getyourguide.com\/queenstown-l498\/queenstown-shotover-canyon-swing-world-s-first-t1281461\/?partner_id=D9DWO5S&amp;utm_medium=online_publisher\" target=\"_blank\" rel=\"sponsored nofollow noopener\">Termine &amp; Preise pr\u00fcfen<\/a>\n\t<small class=\"wttw-affiliate-card__disclosure\">Affiliate-Link: Wenn Du \u00fcber diesen Link buchst, erhalten wir m\u00f6glicherweise eine Provision.<\/small>\n<\/aside>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zusatzkauf:<\/strong> Nach Deinem Sprung kannst Du f\u00fcr NZD 80 einen USB-Stick mit all Deinen Fotos und Videos kaufen. Am Seil sind 2 GoPros befestigt, die jede Sekunde Deines Sprungs aufnehmen. Aus dem Material wird ein sehr sch\u00f6nes kurzes Video produziert, sodass Du den Moment immer wieder genie\u00dfen kannst. Du bekommst au\u00dferdem viele Bilder (darunter eine Serienaufnahme, die Dich beim Abstieg zeigt). Wenn Du nicht das ganze Paket kaufen m\u00f6chtest, kannst Du nat\u00fcrlich auch einzelne Fotos erwerben.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"478\" class=\"wp-image-5265\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-4.jpg\" alt=\"Tom und Bianca mit einem Guide nach dem Shotover Canyon Swing\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-4.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-4-300x169.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-4-768x432.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Shotover-Canyon-Swing-4-705x396.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Lake Wakatipu<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach unserem morgendlichen Spa\u00df in luftiger H\u00f6he fuhren wir zum Lake Wakatipu, um kurz zu schwimmen. Nat\u00fcrlich wollten wir damit auch die fehlenden Duschen auf dem Campingplatz ausgleichen. Das Wetter war nicht gerade ideal: regnerisch, bew\u00f6lkt und nicht wirklich warm. Au\u00dferdem ist der Lake Wakatipu zwar Neuseelands drittgr\u00f6\u00dfter, aber nicht gerade sein w\u00e4rmster See. Wir fuhren zur <strong>Wilson Bay<\/strong>, einem wirklich sch\u00f6nen Ort zum Parken, Kochen und Schwimmen. Vom Zentrum Queenstowns sind es nur rund 10 Fahrminuten, trotzdem ist es dort sehr ruhig. Lake Wakatipu ist der klarste See, den wir in Neuseeland gesehen haben, und sie sind dort alle unglaublich klar. Wir rannten schnell ins Wasser, das so kalt war, dass uns beinahe der Atem stockte. An einem hei\u00dfen, sonnigen Tag k\u00f6nnen wir das Schwimmen in der Wilson Bay absolut empfehlen. Etwas abseits der Menschenmengen ist sie der perfekte Ort f\u00fcr eine kleine Erfrischung.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"637\" class=\"wp-image-5268\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-2.jpg\" alt=\"Luftaufnahme der bewaldeten K\u00fcste am Lake Wakatipu\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-2.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-2-300x225.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-2-768x576.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-2-705x528.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" class=\"wp-image-5267\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-1.jpg\" alt=\"Enten am steinigen Ufer des Lake Wakatipu vor den Bergen\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-1.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-1-300x200.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-1-768x512.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown_New_Zealand-1-705x470.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Cookie Time Cookie Bar Queenstown<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nachdem wir im eiskalten Wasser des Lake Wakatipu beinahe erfroren waren, war es Zeit f\u00fcr den n\u00e4chsten Schock: einen echten Cookie-Time-Zuckerschock. Cookie Time ist in Neuseeland eine riesige Sache. Das Unternehmen produziert im Grunde nur einen Chocolate Chip Cookie und verkauft ihn \u00fcberall. Die Marke ist sehr stark: Cookie-Time-Lieferautos siehst Du \u00fcberall, und das Maskottchen ist ein rotes, flauschiges Cookie Monster. Wir sind total verliebt in die Kekse. Als wir also eine Cookie Time Bar in Queenstown entdeckten, mussten wir hinein. Der Ort ist so cool, fast wie ein kleines Cookie-Time-Disneyland. Ein echter Spa\u00dfort, genau wie wir ihn lieben. Erstens riecht es k\u00f6stlich, nach einer Mischung aus frisch gebackenem Keksteig, warmer Schokolade und Karamell. Zweitens ist die Cookie Bar riesig und bietet alles f\u00fcr echte Keksmonster: Cookies, S&#8217;mores, Cookie Dough, Eis, Shakes und nat\u00fcrlich eine Milchbar. Zu jedem Cookie kannst Du ein Glas Milch Deiner Wahl genie\u00dfen: pur, Schokolade oder Karamell. Nat\u00fcrlich gibt es dort auch ein Cookie Monster in Originalgr\u00f6\u00dfe, das Du umarmen, k\u00fcssen und mit dem Du Fotos machen kannst. Au\u00dferdem steht dort ein halbes Auto, ja, wirklich nur eine H\u00e4lfte. Du kannst darin sitzen. Au\u00dfen ist es \u00fcber und \u00fcber mit Kirschbl\u00fcten bemalt (Bianca liebt Kirschbl\u00fcten), innen mit rotem, flauschigem Cookie-Monster-Fell ausgekleidet. Es gibt auch eine Karaoke-Ecke mit allen m\u00f6glichen Trash-Songs aus den 90ern, die Bianca total liebt (Backstreet Boys, Spice Girls, \u2026), und Disney-Songs. Kurz gesagt: ein total cooler Ort, an dem Du nicht nur all das Cookie-Zeug essen, sondern es auch f\u00fcr zu Hause kaufen kannst. Nach etwa einer Stunde verr\u00fccktem Cookie-Spa\u00df gingen wir mit einer Zucker\u00fcberdosis, aber sehr gl\u00fccklichen Gesichtern wieder hinaus.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" class=\"wp-image-5269\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-1.jpg\" alt=\"Mitarbeiterinnen hinter der Theke der Cookie Time Bar Queenstown\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-1.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-1-300x200.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-1-768x512.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-1-705x470.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" class=\"wp-image-5270\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-2.jpg\" alt=\"Bianca sitzt mit einem Getr\u00e4nk im bunten Cookie-Monster-Auto\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-2.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-2-300x200.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-2-768x512.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-2-705x470.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"850\" class=\"wp-image-5271\" src=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-3.jpg\" alt=\"Tom trinkt einen Shake im Cookie-Monster-Auto\" srcset=\"https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-3.jpg 850w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-3-150x150.jpg 150w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-3-300x300.jpg 300w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-3-768x768.jpg 768w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-3-109x109.jpg 109w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-3-100x100.jpg 100w, https:\/\/wetourtheworld.com\/wp-content\/uploads\/2018\/01\/Queenstown-Cookie-Time-3-705x705.jpg 705w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Queenstown war ein absoluter Knaller. Beim ersten Besuch gefiel es uns nicht besonders, weil wir damals eher Einsamkeit und Ruhe suchten. Diesmal wollten wir Action, Menschen und Abenteuer und fanden all das dort. Wir hatten eine gro\u00dfartige Zeit und werden definitiv zur\u00fcckkommen \u2026 f\u00fcr einen Fergburger und einen Canyon Swing.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Unsere \u00dcbernachtungspl\u00e4tze<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Twelve Mile Delta Campsite<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir verbrachten 2 N\u00e4chte auf dem DOC-Campingplatz Twelve Mile Delta (13 NZD pro Person \/ Nacht). Im Spaceship-Campingpass ist kein Campingplatz in oder nahe Queenstown enthalten, daher mussten wir f\u00fcr diesen bezahlen. Es gibt 2 DOC-Campingpl\u00e4tze nahe Queenstown, beide etwa 15 Fahrminuten vom Zentrum entfernt: Twelve Mile Delta und Moke Lake. Wir entschieden uns f\u00fcr Twelve Mile Delta, weil der Platz wundersch\u00f6n direkt am Lake Wakatipu liegt und riesig ist. Wir kommen meistens sehr sp\u00e4t auf Campingpl\u00e4tzen an, daher ist die Chance auf einen guten Stellplatz bei einem gro\u00dfen Platz immer h\u00f6her als bei einem kleinen. Obwohl auch Moke Lake gro\u00df ist (50 Stellpl\u00e4tze).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Campingplatz ist sehr sch\u00f6n, bietet viele malerische Stellpl\u00e4tze, zwei Toiletten und Sp\u00fclbecken f\u00fcr das Geschirr. Wenn Du m\u00f6chtest, kannst Du auch in den See springen und eine kleine Dusche \/ Erfrischung bekommen.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Unser Queenstown-Erlebnis mit Shotover Canyon Swing, Fergburger, Lake Wakatipu, Cookie Time Bar und praktischen Tipps zu Preisen und Camping.<\/p>\n","protected":false},"author":1,"featured_media":5014,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"Queenstown: Canyon Swing, Fergburger und Reisetipps","_seopress_titles_desc":"Unser Queenstown-Erlebnis mit Shotover Canyon Swing, Fergburger, Lake Wakatipu, Cookie Time Bar sowie praktischen Preis- und Campingtipps.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"https:\/\/wetourtheworld.com\/queenstown-abenteuerhauptstadt\/","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"footnotes":""},"categories":[247,248],"tags":[],"class_list":["post-4925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuseeland","category-ozeanien"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":{"wttw_article_facts":[{"wttw_fact_label":"Reiseziel","wttw_fact_value":"Neuseeland"},{"wttw_fact_label":"Art der Reise","wttw_fact_value":"Stadt und Kultur"},{"wttw_fact_label":"Schwerpunkt","wttw_fact_value":"Queenstown: Neuseelands Abenteuerhauptstadt"}],"wttw_conclusion_title":"Unser Fazit: Hat Queenstown uns diesmal \u00fcberzeugt?","wttw_conclusion_text":"Absolut. Bei unserem ersten Besuch suchten wir Ruhe, diesmal wollten wir Action. Genau die fanden wir in Queenstown: Canyon Swing, gutes Essen und jede Menge Leben rund um den See. F\u00fcr das n\u00e4chste Abenteuer und einen weiteren Fergburger w\u00fcrden wir sofort zur\u00fcckkehren.","wttw_conclusion_quote":"","wttw_disable_ads":false,"wttw_hero_image_position":"center"},"_links":{"self":[{"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/posts\/4925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/comments?post=4925"}],"version-history":[{"count":10,"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/posts\/4925\/revisions"}],"predecessor-version":[{"id":10417,"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/posts\/4925\/revisions\/10417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/media\/5014"}],"wp:attachment":[{"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/media?parent=4925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/categories?post=4925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wetourtheworld.com\/de\/wp-json\/wp\/v2\/tags?post=4925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}